{"id":4567,"date":"2020-02-15T10:35:55","date_gmt":"2020-02-15T03:35:55","guid":{"rendered":"https:\/\/the7.io\/logistics\/?page_id=10"},"modified":"2026-08-05T22:18:55","modified_gmt":"2026-08-05T15:18:55","slug":"home","status":"publish","type":"page","link":"https:\/\/aogtransport.com\/th\/","title":{"rendered":"@aogloblatransport"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4567\" class=\"elementor elementor-4567\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-699f46f elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"699f46f\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-211463e\" data-id=\"211463e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af1f873 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"af1f873\" data-element_type=\"widget\" data-settings=\"{&quot;transition_speed&quot;:1000,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{align-items:center}.elementor--h-position-left .swiper-slide-inner{justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:777px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-8d64be6 swiper-slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--out\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0e40\u0e2d\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15<\/div><div class=\"elementor-slide-description\">\"\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\"<\/div><a href=\"https:\/\/aogtransport.com\/th\/about\/\" class=\"elementor-button elementor-slide-button elementor-size-lg\">\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f35efc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f35efc\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43ea682\" data-id=\"43ea682\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-311476d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"311476d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c135776\" data-id=\"c135776\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-014d7fe elementor-widget elementor-widget-heading\" data-id=\"014d7fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.2 - 11-05-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">\u0e22\u0e34\u0e19\u0e14\u0e35\u0e15\u0e2d\u0e19\u0e23\u0e31\u0e1a <br>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bff3f9 elementor-widget elementor-widget-spacer\" data-id=\"0bff3f9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.2 - 11-05-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dbff80 elementor-widget elementor-widget-heading\" data-id=\"0dbff80\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u2013 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb87f3 elementor-widget elementor-widget-spacer\" data-id=\"9fb87f3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0506553\" data-id=\"0506553\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98a462d elementor-widget elementor-widget-video\" data-id=\"98a462d\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/CgrKk5MiTvQ&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.2 - 11-05-2023 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;left:0;width:100%;height:100%;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c4d0280 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7c4d0280\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2833226d\" data-id=\"2833226d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76520899 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"76520899\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.2 - 11-05-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40ec193 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"40ec193\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bfc22d\" data-id=\"8bfc22d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77d5e17 elementor-widget elementor-widget-heading\" data-id=\"77d5e17\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-508da35\" data-id=\"508da35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2358e20 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"2358e20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A full range of quality logistic services<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a77a852 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6a77a852\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cb7b84e\" data-id=\"2cb7b84e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da62825 arrows-relative-to-image preserve-img-ratio-cover bullets-small-dot-stroke elementor-widget elementor-widget-the7_elements_carousel\" data-id=\"da62825\" data-element_type=\"widget\" data-widget_type=\"the7_elements_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"carousel-nav-display-always   the7_elements_carousel-da62825 owl-carousel portfolio-carousel-shortcode elementor-owl-carousel-call portfolio-shortcode the7-elementor-widget content-bg-on classic-layout-list description-under-image meta-info-off\" data-scroll-mode=\"1\" data-col-num=\"3\" data-wide-col-num=\"3\" data-laptop-col=\"2\" data-h-tablet-columns-num=\"2\" data-v-tablet-columns-num=\"2\" data-phone-columns-num=\"1\" data-auto-height=\"false\" data-col-gap=\"60\" data-col-gap-tablet=\"30\" data-col-gap-mobile=\"\" data-speed=\"600\" data-autoplay=\"false\" data-autoplay_speed=\"\"><article class=\"post visible post-131 services type-services status-publish has-post-thumbnail hentry service_category-additional-services\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/one-stop-service\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201707&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1707;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-300x200.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-1024x683.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-768x512.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-1536x1024.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-2048x1365.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/business-man-financial-inspector-secretary-making-report-calculating-checking-balance-internal-revenue-service-inspector-checking-document-audit-concept-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/one-stop-service\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/one-stop-service\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 - \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 - \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/one-stop-service\/\" target=\"\" aria-label=\"Read more about One Stop Service\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-1128 services type-services status-publish has-post-thumbnail hentry service_category-transportation\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/sea-freigh\/\"><img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201707&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1707;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-300x200.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-1024x683.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-768x512.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-1536x1024.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-2048x1365.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/01\/aerial-view-cargo-ship-cargo-container-harbor-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/sea-freigh\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/sea-freigh\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/sea-freigh\/\" target=\"\" aria-label=\"Read more about Sea freight\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-1085 services type-services status-publish has-post-thumbnail hentry service_category-transportation\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/air-freight\/\"><img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201920&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1920;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-300x225.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-1024x768.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-768x576.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-1536x1152.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-2048x1536.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-1265683616-16x12.jpg 16w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/air-freight\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/air-freight\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/air-freight\/\" target=\"\" aria-label=\"Read more about Air freight\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-135 services type-services status-publish has-post-thumbnail hentry service_category-additional-services\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/customs-clearance\/\"><img decoding=\"async\" width=\"2560\" height=\"1855\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201855&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1855;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-300x217.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-1024x742.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-768x557.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-1536x1113.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-2048x1484.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/customs-declaration-form-invoice-freight-parcel-concept-2-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/customs-clearance\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/customs-clearance\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/customs-clearance\/\" target=\"\" aria-label=\"Read more about Customs Clearance\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-1122 services type-services status-publish has-post-thumbnail hentry service_category-transportation\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/trucking\/\"><img decoding=\"async\" width=\"2560\" height=\"1738\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201738&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1738;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-300x204.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-1024x695.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-768x521.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-1536x1043.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-2048x1390.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/trucks-parked-lined-up-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/trucking\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/trucking\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/trucking\/\" target=\"\" aria-label=\"Read more about Trucking\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-141 services type-services status-publish has-post-thumbnail hentry service_category-storage\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/warehousing\/\"><img decoding=\"async\" width=\"2560\" height=\"1708\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201708&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1708;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-300x200.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-1024x683.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-768x512.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-1536x1025.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-2048x1366.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2023\/01\/iStock-1408363818-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/warehousing\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/warehousing\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/warehousing\/\" target=\"\" aria-label=\"Read more about Warehousing\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-1095 services type-services status-publish has-post-thumbnail hentry service_category-additional-services\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/packing-fumigation\/\"><img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201440&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1440;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-300x169.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-1024x576.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-768x432.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-1536x864.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-2048x1152.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-658927230-18x10.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/packing-fumigation\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/packing-fumigation\/\" rel=\"bookmark\" title=\"Packing &#038; fumigation\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e21\u0e22\u0e32<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/packing-fumigation\/\" target=\"\" aria-label=\"Read more about Packing &#038; fumigation\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><article class=\"post visible post-138 services type-services status-publish has-post-thumbnail hentry service_category-additional-services\">\n\n\t<div class=\"post-thumbnail-wrap rollover-active\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Post image\" href=\"https:\/\/aogtransport.com\/th\/services\/multimodal-transport\/\"><img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201707&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1707;\" data-src=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-scaled.jpg 2560w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-300x200.jpg 300w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-1024x683.jpg 1024w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-768x512.jpg 768w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-1536x1024.jpg 1536w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-2048x1365.jpg 2048w, https:\/\/aogtransport.com\/wp-content\/uploads\/2020\/02\/iStock-700822026-18x12.jpg 18w\" \/><\/a><div class=\"project-links-container\"><a href=\"https:\/\/aogtransport.com\/th\/services\/multimodal-transport\/\" class=\"project-details\" aria-label=\"Details link\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ellipsis-h\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M328 256c0 39.8-32.2 72-72 72s-72-32.2-72-72 32.2-72 72-72 72 32.2 72 72zm104-72c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72zm-352 0c-39.8 0-72 32.2-72 72s32.2 72 72 72 72-32.2 72-72-32.2-72-72-72z\"><\/path><\/svg><\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h4 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/services\/multimodal-transport\/\" rel=\"bookmark\" title=\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a<\/a><\/h4><a href=\"https:\/\/aogtransport.com\/th\/services\/multimodal-transport\/\" target=\"\" aria-label=\"Read more about Multimodal Transport\" class=\"box-button elementor-button elementor-size-xs\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\n<\/div><\/article><\/div><div class=\"owl-nav disabled\"><a class=\"owl-prev\" role=\"button\"><svg class=\"e-font-icon-svg e-fas-chevron-left\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.52 239.03L228.87 44.69c9.37-9.37 24.57-9.37 33.94 0l22.67 22.67c9.36 9.36 9.37 24.52.04 33.9L131.49 256l154.02 154.75c9.34 9.38 9.32 24.54-.04 33.9l-22.67 22.67c-9.37 9.37-24.57 9.37-33.94 0L34.52 272.97c-9.37-9.37-9.37-24.57 0-33.94z\"><\/path><\/svg><\/a><a class=\"owl-next\" role=\"button\"><svg class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00dc3e2 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"00dc3e2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63b0df5\" data-id=\"63b0df5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac45a7 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5ac45a7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-991f2d2 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"991f2d2\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3ad7f1\" data-id=\"d3ad7f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59d5302 elementor-widget elementor-widget-heading\" data-id=\"59d5302\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">News & info<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-442ce59\" data-id=\"442ce59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-610bfaf elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"610bfaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Latest company news & announcements<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4f22e8 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"b4f22e8\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fe6bd6e\" data-id=\"fe6bd6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0d7746 preserve-img-ratio-cover elementor-widget elementor-widget-the7_elements\" data-id=\"c0d7746\" data-element_type=\"widget\" data-widget_type=\"the7_elements.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"portfolio-shortcode the7-elementor-widget the7_elements-c0d7746 mode-grid dt-css-grid-wrap classic-layout-list description-under-image content-bg-on resize-by-browser-width loading-effect-none jquery-filter\" data-padding=\"60px\" data-mobile-columns-num=\"1\" data-tablet-columns-num=\"2\" data-desktop-columns-num=\"2\" data-wide-desktop-columns-num=\"2\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-scroll-offset=\"\"><div class=\"dt-css-grid custom-pagination-handler\"><div class=\"visible wf-cell\" data-post-id=\"6847\" data-date=\"2024-01-23T23:35:19+07:00\" data-name=\"windows 7 activate download free \u2713 Activate Windows 7 Now! \u2794 Easy Steps to Bypass Activation\"><article class=\"post visible no-img post-6847 type-post status-publish format-standard hentry category-uncategorized\" data-name=\"windows 7 activate download free \u2713 Activate Windows 7 Now! \u2794 Easy Steps to Bypass Activation\" data-date=\"2024-01-23T23:35:19+07:00\">\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/windows-7-activate-download-free\/\" rel=\"bookmark\" title=\"windows 7 activate download free \u2713 Activate Windows 7 Now! \u2794 Easy Steps to Bypass Activation\">windows 7 activate download free \u2713 Activate Windows 7 Now! \u2794 Easy Steps to Bypass Activation<\/a><\/h3><div class=\"entry-meta\"><a href=\"https:\/\/aogtransport.com\/th\/2024\/01\/23\/\" title=\"11:35 pm\" class=\"meta-item data-link\" rel=\"bookmark\"><time class=\"entry-date updated\" datetime=\"2024-01-23T23:35:19+07:00\">23\/01\/2024<\/time><\/a><\/div>\n<\/div><\/article><\/div><div class=\"visible wf-cell\" data-post-id=\"6864\" data-date=\"2022-01-23T23:35:19+07:00\" data-name=\"kmspico windows 10 pro \u2713 Activate Windows 10 Pro Now \u27a4 Safe &amp; Offline Tool\"><article class=\"post visible no-img post-6864 type-post status-publish format-standard hentry category-uncategorized\" data-name=\"kmspico windows 10 pro \u2713 Activate Windows 10 Pro Now \u27a4 Safe &#038; Offline Tool\" data-date=\"2022-01-23T23:35:19+07:00\">\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/aogtransport.com\/th\/kmspico-windows-10-pro\/\" rel=\"bookmark\" title=\"kmspico windows 10 pro \u2713 Activate Windows 10 Pro Now \u27a4 Safe &#038; Offline Tool\">kmspico windows 10 pro \u2713 Activate Windows 10 Pro Now \u27a4 Safe &#038; Offline Tool<\/a><\/h3><div class=\"entry-meta\"><a href=\"https:\/\/aogtransport.com\/th\/2022\/01\/23\/\" title=\"11:35 pm\" class=\"meta-item data-link\" rel=\"bookmark\"><time class=\"entry-date updated\" datetime=\"2022-01-23T23:35:19+07:00\">23\/01\/2022<\/time><\/a><\/div>\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-827a214\" data-id=\"827a214\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1d0025 icon-box-vertical-align-top slide-h-position-left elementor-widget elementor-widget-the7-elements-simple-posts\" data-id=\"f1d0025\" data-element_type=\"widget\" data-widget_type=\"the7-elements-simple-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-simple-widget-posts the7-elementor-widget the7-elements-simple-posts-f1d0025 jquery-filter hide-post-image jquery-filter\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-scroll-offset=\"\">\t\t\t<div class=\"dt-css-grid custom-pagination-handler\" data-columns=\"{&quot;d&quot;:1,&quot;t&quot;:2,&quot;p&quot;:1,&quot;wd&quot;:&quot;&quot;}\">\n\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible\">\n\t\t\t\t\t\t<article class=\"post visible wrapper no-img post-6861 type-post status-publish format-standard hentry category-uncategorized\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h5 class=\"heading\"><a href=\"https:\/\/aogtransport.com\/th\/windows-7-activator-software\/\" rel=\"bookmark\" title=\"Windows 7 Activator Software \u2713 Activate 32 &#038; 64-bit OS Fast\" class=\"post-title\">Windows 7 Activator Software \u2713 Activate 32 &#038; 64-bit OS Fast<\/a><\/h5><div class=\"entry-meta\"><span class=\"meta-item data-link\"><time class=\"entry-date updated\" datetime=\"2022-01-23T23:35:19+07:00\">23\/01\/2022<\/time><\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\t\t<div class=\"wf-cell visible\">\n\t\t\t\t\t\t<article class=\"post visible wrapper no-img post-6858 type-post status-publish format-standard hentry category-uncategorized\">\n\n\t\t\t\t\t\t\t<div class=\"post-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-entry-content\">\n\t\t\t\t\t\t\t\t\t<h5 class=\"heading\"><a href=\"https:\/\/aogtransport.com\/th\/dark-porn-telegram\/\" rel=\"bookmark\" title=\"dark porn telegram Join the Best Telegram Groups \u2713 5 Stars!\" class=\"post-title\">dark porn telegram Join the Best Telegram Groups \u2713 5 Stars!<\/a><\/h5><div class=\"entry-meta\"><span class=\"meta-item data-link\"><time class=\"entry-date updated\" datetime=\"2022-01-23T23:35:19+07:00\">23\/01\/2022<\/time><\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d54107f elementor-widget elementor-widget-spacer\" data-id=\"d54107f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23daa37 elementor-invisible elementor-widget elementor-widget-the7_button_widget\" data-id=\"23daa37\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"https:\/\/aogtransport.com\/th\/news\/\" class=\"box-button elementor-button elementor-size-md\">MORE ARTICLES<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-255e71dd elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"255e71dd\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-250e03cd\" data-id=\"250e03cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32062fdc elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"32062fdc\" data-element_type=\"widget\" data-e-bg-lazyload=\".elementor-flip-box__front, .elementor-flip-box__back\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/aogtransport.com\/wp-content\/uploads\/elementor\/css\/custom-pro-widget-flip-box.min.css?ver=1684741696\">\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-md\" href=\"https:\/\/www.customs.go.th\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tWeb site\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4201c21\" data-id=\"4201c21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00421f6 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"00421f6\" data-element_type=\"widget\" data-e-bg-lazyload=\".elementor-flip-box__front, .elementor-flip-box__back\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t \u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-md\" href=\"https:\/\/www.port.co.th\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tWeb site\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6e3aece4\" data-id=\"6e3aece4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22cc50f3 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"22cc50f3\" data-element_type=\"widget\" data-e-bg-lazyload=\".elementor-flip-box__front, .elementor-flip-box__back\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e17\u0e22\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-md\" href=\"https:\/\/www.airportthai.co.th\/th\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tweb site\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ed54a2b\" data-id=\"ed54a2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2510be5 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"2510be5\" data-element_type=\"widget\" data-e-bg-lazyload=\".elementor-flip-box__front, .elementor-flip-box__back\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\u0e01\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-md\" href=\"https:\/\/www.dbd.go.th\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tWeb site\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>AO GLOBAL TRANSPORT THAILAND\u201cEasy, Quick, Cheap and Friendly\u201dAbout Welcome Ao global transport Co., Ltd We are Thai company engaged in the international freight forwarder business. Services A full range of quality logistic services One Stop Service Read more Sea freight Read more Air freight Read more Customs Clearance Read more Trucking The visual concept of&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-4567","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/pages\/4567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/comments?post=4567"}],"version-history":[{"count":266,"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/pages\/4567\/revisions"}],"predecessor-version":[{"id":6831,"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/pages\/4567\/revisions\/6831"}],"wp:attachment":[{"href":"https:\/\/aogtransport.com\/th\/wp-json\/wp\/v2\/media?parent=4567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}